{"id":4157,"date":"2024-11-23T04:58:20","date_gmt":"2024-11-23T04:58:20","guid":{"rendered":"https:\/\/support-landing.altegio.cloud\/support\/4856849625117\/"},"modified":"2025-10-31T08:56:18","modified_gmt":"2025-10-31T08:56:18","password":"","slug":"4856849625117","status":"publish","type":"docs","link":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/4856849625117\/","title":{"rendered":"Trabalhando com o Calend\u00e1rio de Servi\u00e7os"},"content":{"rendered":"<h2>O que \u00e9 e para que serve?<\/h2>\n<p>O <strong>Calend\u00e1rio de Servi\u00e7os<\/strong> \u00e9 um calend\u00e1rio digital que permite gerenciar hor\u00e1rios e compromissos.<\/p>\n<p>O calend\u00e1rio oferece suporte \u00e0 colabora\u00e7\u00e3o, permitindo que v\u00e1rios usu\u00e1rios trabalhem nele simultaneamente. Os administradores t\u00eam o privil\u00e9gio de manter e gerenciar o calend\u00e1rio, enquanto os funcion\u00e1rios podem acessar convenientemente suas agendas e visualizar reservas. Este sistema centralizado armazena todas os agendamentos e eventos existentes, que s\u00e3o criados pelo administrador atrav\u00e9s da funcionalidade <strong>Calend\u00e1rio de Servi\u00e7os<\/strong>, bem como pelos clientes atrav\u00e9s do pr\u00e1tico widget de <strong>Agendamento Online<\/strong>.<\/p>\n<h2>Para come\u00e7ar<\/h2>\n<p>Antes de come\u00e7ar a trabalhar com o calend\u00e1rio, \u00e9 crucial garantir que o processo de configura\u00e7\u00e3o foi conclu\u00eddo. Isso envolve adicionar <a href=\"https:\/\/alteg.io\/support\/support\/pt-br\/knowledge-base\/categories\/categorias-e-servicos\/\" target=\"_self\" rel=\"noopener\">servi\u00e7os<\/a>, <a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4846102787357-Adicionando-a-equipe\" target=\"_self\" rel=\"noopener\">equipe<\/a> e <a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4869516836637-Recursos\" target=\"_self\" rel=\"noopener\">recursos<\/a> necess\u00e1rios ao sistema e estabelecer um <a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4846242960925-Hor%C3%A1rio-de-Trabalho\" target=\"_self\" rel=\"noopener\">hor\u00e1rio de trabalho<\/a> abrangente.<\/p>\n<p>Para ir ao <strong>Calend\u00e1rio de Servi\u00e7os<\/strong>, selecione uma data no calend\u00e1rio na parte superior do menu principal.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12006858321181-1000x553.png\" \/><\/p>\n<h2>Trabalhando com o Calend\u00e1rio de Servi\u00e7os<\/h2>\n<p>O <strong>Calend\u00e1rio de Servi\u00e7os<\/strong> est\u00e1 equipado com v\u00e1rios bot\u00f5es localizados no painel superior, que permitem controlar v\u00e1rias fun\u00e7\u00f5es.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12006823949597-1000x37.png\" \/><\/p>\n<ul>\n<li>Clique no bot\u00e3o com <strong>tr\u00eas barras<\/strong> <img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12006893102109.png\" \/> para ocultar ou expandir o menu lateral esquerdo.<\/li>\n<li>Use os <strong>bot\u00f5es de seta<\/strong> <img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12006900404765.png\" \/>\u00a0para percorrer os dias no calend\u00e1rio. Para retornar \u00e0 data atual, basta pressionar o bot\u00e3o &#8220;<strong>Hoje<\/strong>&#8220;.<\/li>\n<li>Veja as <strong>estat\u00edsticas financeiras<\/strong> do dia clicando no bot\u00e3o com a soma \u00e0 direita. Esta se\u00e7\u00e3o fornece informa\u00e7\u00f5es sobre o faturamento em dinheiro ou outros meios, os valores das reservas criadas, a parte do valor paga com pontos de fidelidade e os descontos.\n<p><strong>IMPORTANTE<\/strong><\/p>\n<p data-start=\"143\" data-end=\"290\">Para conceder a um funcion\u00e1rio acesso \u00e0 <strong data-start=\"183\" data-end=\"210\">an\u00e1lise di\u00e1ria do caixa<\/strong> no <strong data-start=\"214\" data-end=\"240\">Di\u00e1rio de agendamentos<\/strong>, \u00e9 necess\u00e1rio fornecer as seguintes permiss\u00f5es:<\/p>\n<ul data-start=\"292\" data-end=\"478\">\n<li data-start=\"292\" data-end=\"368\">\n<p data-start=\"294\" data-end=\"368\">Permiss\u00e3o <strong data-start=\"304\" data-end=\"329\">\u201cExibir estat\u00edsticas\u201d<\/strong> na se\u00e7\u00e3o <strong data-start=\"339\" data-end=\"365\">Di\u00e1rio de agendamentos<\/strong>.<\/p>\n<\/li>\n<li data-start=\"369\" data-end=\"478\">\n<p data-start=\"371\" data-end=\"478\">Acesso \u00e0 permiss\u00e3o raiz <strong data-start=\"395\" data-end=\"408\">\u201cEstoque\u201d<\/strong> (n\u00e3o \u00e9 necess\u00e1rio atribuir permiss\u00f5es internas dentro desta se\u00e7\u00e3o).<\/p>\n<\/li>\n<\/ul>\n<p>Tamb\u00e9m pode utilizar o bot\u00e3o &#8220;<strong>Vender um produto<\/strong>&#8221; na mesma janela para indicar a venda de produtos a clientes, mesmo que n\u00e3o tenham marca\u00e7\u00f5es no <strong>Calend\u00e1rio de Servi\u00e7os<\/strong> para esse dia.<\/li>\n<\/ul>\n<p>Leia mais sobre essa funcionalidade neste <a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4850830180637-Vendas-de-produtos-usando-uma-opera%C3%A7%C3%A3o-de-estoque\" target=\"_self\" rel=\"noopener\">artigo<\/a>.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12006924288925.png\" \/><\/p>\n<ul>\n<li>A op\u00e7\u00e3o &#8220;<strong>Dia<\/strong>&#8221; permite <strong>visualizar a programa\u00e7\u00e3o do dia para todos os profissionais da equipe<\/strong> em todos os cargos ou para uma posi\u00e7\u00e3o espec\u00edfica, bem como a programa\u00e7\u00e3o dos recursos.<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12006973022621.png\" \/><\/p>\n<ul>\n<li>A op\u00e7\u00e3o &#8220;<strong>Semana<\/strong>&#8221; permite visualizar a programa\u00e7\u00e3o da semana para um <strong>funcion\u00e1rio<\/strong> ou <a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4869516836637-Recursos\" target=\"_self\" rel=\"noopener\">recurso espec\u00edfico<\/a>.<\/li>\n<li>Voc\u00ea pode <a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4856828907549-Tamanho-do-Calend%C3%A1rio\" target=\"_self\" rel=\"noopener\">alterar o tamanho<\/a> do Calend\u00e1rio de Servi\u00e7os clicando no <strong>bot\u00e3o da lupa<\/strong> <img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/21086861111837.png\" alt=\"vnIy1iqj23Jczm6exlKAwOyyeQ1t7hC4isI0rHOK.png\" \/>.<br \/>\nAl\u00e9m disso, voc\u00ea pode adicionar funcion\u00e1rios \u00e0 programa\u00e7\u00e3o de um dia espec\u00edfico clicando no <strong>bot\u00e3o da pessoa com s\u00edmbolo de adi\u00e7\u00e3o<\/strong> <img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/21086861113117.png\" alt=\"kAdhjkbg63rDHBkCtXTrqkmCvWIXUvo7BBYPLJzg.png\" \/>.<\/li>\n<li>Usando o bot\u00e3o de filtro <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/21086861116189.png\" width=\"25\" height=\"27\" \/>, voc\u00ea pode filtrar todas as visitas por seu <a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4856840660637-Status-dos-compromissos\" target=\"_self\" rel=\"noopener\">status<\/a>.<br \/>\nPor exemplo, voc\u00ea pode ocultar todas as visitas com o status &#8220;O cliente n\u00e3o veio&#8221; para que n\u00e3o interfiram na cria\u00e7\u00e3o de novos agendamentos no calend\u00e1rio.<\/li>\n<\/ul>\n<p><strong>Importante<\/strong>: voc\u00ea pode filtrar apenas reservas individuais, o filtro n\u00e3o afeta os eventos do grupo.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12007024153373.png\" \/><\/p>\n<ul>\n<li>Acesse o painel de pesquisa de clientes clicando no <strong>bot\u00e3o sorridente<\/strong> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/21086861116829.png\" width=\"32\" height=\"35\" \/> localizado no canto superior direito.<\/li>\n<li>Para <strong>modificar o hor\u00e1rio de trabalho<\/strong> ou <strong>remover um dia de trabalho<\/strong>, clique no nome do funcion\u00e1rio e escolha a a\u00e7\u00e3o apropriada entre as op\u00e7\u00f5es dispon\u00edveis.<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12007111081373.png\" \/><\/p>\n<h2>Criando novas reservas<\/h2>\n<p>Para criar um <strong>novo agendamento<\/strong> no Calend\u00e1rio de Servi\u00e7os, siga os seguintes passos:<\/p>\n<ol>\n<li>Clique na data para a qual deseja criar uma reserva no Calend\u00e1rio de Servi\u00e7os e a programa\u00e7\u00e3o desse dia aparecer\u00e1.<\/li>\n<li>Selecione o funcion\u00e1rio e o hor\u00e1rio para o qual deseja criar um compromisso. Clique no bot\u00e3o de agendamento que aparece quando voc\u00ea clica em um hor\u00e1rio livre no Calend\u00e1rio de Servi\u00e7os. Especifique o tipo de compromisso como &#8220;<strong>Agendamento<\/strong>&#8221; ou &#8220;<strong>Evento<\/strong>&#8220;.<span style=\"font-size: 1.5em;\"><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12007115993373.png\" \/><\/span><\/li>\n<li>O bot\u00e3o &#8220;<strong>Evento<\/strong>&#8221; permite criar um compromisso de grupo, e voc\u00ea pode ler sobre isso com mais detalhes no artigo &#8220;<a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4860024015773-Configurando-eventos-reserva-de-grupo-\" target=\"_self\" rel=\"noopener\">Configurar eventos<\/a>&#8220;.<\/li>\n<li>O bot\u00e3o &#8220;<strong>Agendamento<\/strong>&#8221; permite que voc\u00ea crie um compromisso individual, e voc\u00ea pode ler sobre isso com mais detalhes no artigo &#8220;<a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4850852124317-Configura%C3%A7%C3%B5es-do-Calend%C3%A1rio-de-Servi%C3%A7os\" target=\"_self\" rel=\"noopener\">Configura\u00e7\u00f5es do Calend\u00e1rio de Servi\u00e7os<\/a>&#8220;.<\/li>\n<\/ol>\n<p>Voc\u00ea ver\u00e1 um cabe\u00e7alho verde se o agendamento foi criado por seu <strong>administrador<\/strong> ou outro funcion\u00e1rio com o <strong>acesso para criar agendamentos<\/strong> no <strong>Calend\u00e1rio de Servi\u00e7os<\/strong>.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12007194091805.png\" \/><\/p>\n<p>O cabe\u00e7alho da <strong>reserva online criada pelo cliente <\/strong>ser\u00e1 <strong>roxo<\/strong>.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/alteg.io\/support\/wp-content\/uploads\/2024\/12\/12007174147229.png\" \/><\/p>\n<p>A cor das reservas pode mudar dependendo do seu <a href=\"https:\/\/support.alteg.io\/hc\/pt-br\/articles\/4856840660637-Status-dos-compromissos\" target=\"_self\" rel=\"noopener\">status<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 e para que serve? O Calend\u00e1rio de Servi\u00e7os \u00e9 um calend\u00e1rio digital que permite gerenciar hor\u00e1rios e compromissos. O calend\u00e1rio oferece suporte \u00e0 colabora\u00e7\u00e3o, permitindo que v\u00e1rios usu\u00e1rios trabalhem nele simultaneamente. Os administradores t\u00eam o privil\u00e9gio de manter e gerenciar o calend\u00e1rio, enquanto os funcion\u00e1rios podem acessar convenientemente suas agendas e visualizar [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[328],"doc_tag":[1468,1513,1513,1348,1483,1840,1288,1615,1498],"class_list":{"0":"post-4157","1":"docs","2":"type-docs","3":"status-publish","4":"hentry","5":"doc_category-como-trabalhar-com-o-calendario-de-servicos","6":"doc_tag-agendamento-pt-br","7":"doc_tag-cliente-pt-br","9":"doc_tag-equipe-pt-br","10":"doc_tag-evento-pt-br","11":"doc_tag-financas-pt-br","12":"doc_tag-recursos-pt-br","13":"doc_tag-reserva-online-pt-br","14":"doc_tag-visita-pt-br"},"aioseo_notices":[],"year_month":"2026-05","word_count":781,"total_views":"102","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"andrei.k@alteg.io","author_nicename":"andrei-kalteg-io","author_url":"https:\/\/alteg.io\/pt\/author\/andrei-kalteg-io\/"},"doc_category_info":[{"term_name":"Como trabalhar com o calend\u00e1rio de servi\u00e7os","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/categories\/como-trabalhar-com-o-calendario-de-servicos\/"}],"doc_tag_info":[{"term_name":"Agendamento","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/agendamento-pt-br\/"},{"term_name":"Cliente","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/cliente-pt-br\/"},{"term_name":"Cliente","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/cliente-pt-br\/"},{"term_name":"Equipe","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/equipe-pt-br\/"},{"term_name":"Evento","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/evento-pt-br\/"},{"term_name":"Finan\u00e7as","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/financas-pt-br\/"},{"term_name":"Recursos","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/recursos-pt-br\/"},{"term_name":"Reserva Online","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/reserva-online-pt-br\/"},{"term_name":"Visita","term_url":"https:\/\/alteg.io\/pt\/support\/knowledge-base\/docs-tag\/visita-pt-br\/"}],"knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/docs\/4157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/comments?post=4157"}],"version-history":[{"count":3,"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/docs\/4157\/revisions"}],"predecessor-version":[{"id":186484,"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/docs\/4157\/revisions\/186484"}],"wp:attachment":[{"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/media?parent=4157"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/doc_category?post=4157"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/alteg.io\/pt\/support\/wp-json\/wp\/v2\/doc_tag?post=4157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}